{"id":6984,"date":"2019-10-04T17:13:35","date_gmt":"2019-10-04T17:13:35","guid":{"rendered":"https:\/\/powermasterinc.com\/?post_type=product&#038;p=6984"},"modified":"2026-08-21T22:20:31","modified_gmt":"2026-08-21T22:20:31","slug":"dsp-10","status":"publish","type":"product","link":"https:\/\/powermasterinc.com\/es\/repuestos\/transferencia-automaticas\/ts-con-gabinete\/dsp-10\/","title":{"rendered":"DSP-10 | Unidad de Control para Generador"},"content":{"rendered":"<p>El DSP-10 (KP-DSP-10) es un M\u00f3dulo de Visualizaci\u00f3n Simple basado en microprocesador, dise\u00f1ado para sistemas de control de generadores. Su dise\u00f1o modular permite una instalaci\u00f3n y reemplazo r\u00e1pidos en los m\u00f3dulos de control GCU-10 y GCU-100. Es el primer y \u00fanico m\u00f3dulo de visualizaci\u00f3n multifunci\u00f3n dise\u00f1ado especialmente para grupos electr\u00f3genos.<\/p>\n<p>Cuenta con tres conjuntos de cuatro pantallas digitales de 7 segmentos que muestran par\u00e1metros operativos clave del generador en tiempo real, permitiendo al operador monitorear el estado del equipo de manera clara y eficiente.<\/p>\n","protected":false},"excerpt":{"rendered":"<ul>\n<li><strong>Primer y \u00fanico M\u00f3dulo de Visualizaci\u00f3n Multifunci\u00f3n<\/strong> dise\u00f1ado especialmente para grupos electr\u00f3genos<\/li>\n<li><strong>Tres conjuntos de cuatro pantallas digitales<\/strong> de 7 segmentos<\/li>\n<li><strong>Dise\u00f1o modular<\/strong> que permite instalaci\u00f3n y configuraci\u00f3n r\u00e1pidas<\/li>\n<li><strong>Compatible con<\/strong> el m\u00f3dulo de control GCU-10 y GCU-100<\/li>\n<\/ul>\n","protected":false},"featured_media":15904,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_joinchat":[]},"product_brand":[],"product_cat":[299],"product_tag":[300,1077,297],"class_list":["post-6984","product","type-product","status-publish","has-post-thumbnail","product_cat-ts-con-gabinete","product_tag-ats","product_tag-dsp-10","product_tag-mcpherson-controls","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DSP10 repuesto generador | Power Master Inc.<\/title>\n<meta name=\"description\" content=\"DSP-10 | Unidad de Control para Generador (DSP10) \u2014 Unidad de control universal programable para generadores. Monitoreo, protecci\u00f3n y arranque autom\u00e1tico. En stock.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/powermasterinc.com\/es\/repuestos\/transferencia-automaticas\/ts-con-gabinete\/dsp-10\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DSP10 repuesto generador | Power Master Inc.\" \/>\n<meta property=\"og:description\" content=\"DSP-10 | Unidad de Control para Generador (DSP10) \u2014 Unidad de control universal programable para generadores. Monitoreo, protecci\u00f3n y arranque autom\u00e1tico. En stock.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/powermasterinc.com\/es\/repuestos\/transferencia-automaticas\/ts-con-gabinete\/dsp-10\/\" \/>\n<meta property=\"og:site_name\" content=\"Power Master Inc.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Power-Master-International-2113343258712341\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-21T22:20:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/powermasterinc.com\/es\/wp-content\/uploads\/2026\/02\/dsp10-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/powermasterinc.com\\\/es\\\/repuestos\\\/transferencia-automaticas\\\/ts-con-gabinete\\\/dsp-10\\\/\",\"url\":\"https:\\\/\\\/powermasterinc.com\\\/es\\\/repuestos\\\/transferencia-automaticas\\\/ts-con-gabinete\\\/dsp-10\\\/\",\"name\":\"DSP10 repuesto generador | Power Master Inc.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/powermasterinc.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/powermasterinc.com\\\/es\\\/repuestos\\\/transferencia-automaticas\\\/ts-con-gabinete\\\/dsp-10\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/powermasterinc.com\\\/es\\\/repuestos\\\/transferencia-automaticas\\\/ts-con-gabinete\\\/dsp-10\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/powermasterinc.com\\\/es\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/dsp10-1.jpg\",\"datePublished\":\"2019-10-04T17:13:35+00:00\",\"dateModified\":\"2026-08-21T22:20:31+00:00\",\"description\":\"DSP-10 | Unidad de Control para Generador (DSP10) \u2014 Unidad de control universal programable para generadores. Monitoreo, protecci\u00f3n y arranque autom\u00e1tico. En stock.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/powermasterinc.com\\\/es\\\/repuestos\\\/transferencia-automaticas\\\/ts-con-gabinete\\\/dsp-10\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/powermasterinc.com\\\/es\\\/repuestos\\\/transferencia-automaticas\\\/ts-con-gabinete\\\/dsp-10\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/powermasterinc.com\\\/es\\\/repuestos\\\/transferencia-automaticas\\\/ts-con-gabinete\\\/dsp-10\\\/#primaryimage\",\"url\":\"https:\\\/\\\/powermasterinc.com\\\/es\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/dsp10-1.jpg\",\"contentUrl\":\"https:\\\/\\\/powermasterinc.com\\\/es\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/dsp10-1.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"DSP10 repuesto para generadores y motores industriales\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/powermasterinc.com\\\/es\\\/repuestos\\\/transferencia-automaticas\\\/ts-con-gabinete\\\/dsp-10\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/powermasterinc.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/powermasterinc.com\\\/es\\\/tienda-proveedor-repuestos-para-generadores-de-energia\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"DSP-10 | Unidad de Control para Generador\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/powermasterinc.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/powermasterinc.com\\\/es\\\/\",\"name\":\"Power Master Inc.\",\"description\":\"Todo en un solo Lugar | \u00a1Para todas sus necesidades de generaci\u00f3n el\u00e9ctrica!\",\"publisher\":{\"@id\":\"https:\\\/\\\/powermasterinc.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/powermasterinc.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/powermasterinc.com\\\/es\\\/#organization\",\"name\":\"Power Master International\",\"url\":\"https:\\\/\\\/powermasterinc.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/powermasterinc.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Power Master International\"},\"image\":{\"@id\":\"https:\\\/\\\/powermasterinc.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Power-Master-International-2113343258712341\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DSP10 repuesto generador | Power Master Inc.","description":"DSP-10 | Unidad de Control para Generador (DSP10) \u2014 Unidad de control universal programable para generadores. Monitoreo, protecci\u00f3n y arranque autom\u00e1tico. En stock.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/powermasterinc.com\/es\/repuestos\/transferencia-automaticas\/ts-con-gabinete\/dsp-10\/","og_locale":"es_ES","og_type":"article","og_title":"DSP10 repuesto generador | Power Master Inc.","og_description":"DSP-10 | Unidad de Control para Generador (DSP10) \u2014 Unidad de control universal programable para generadores. Monitoreo, protecci\u00f3n y arranque autom\u00e1tico. En stock.","og_url":"https:\/\/powermasterinc.com\/es\/repuestos\/transferencia-automaticas\/ts-con-gabinete\/dsp-10\/","og_site_name":"Power Master Inc.","article_publisher":"https:\/\/www.facebook.com\/Power-Master-International-2113343258712341\/","article_modified_time":"2026-08-21T22:20:31+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/powermasterinc.com\/es\/wp-content\/uploads\/2026\/02\/dsp10-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/powermasterinc.com\/es\/repuestos\/transferencia-automaticas\/ts-con-gabinete\/dsp-10\/","url":"https:\/\/powermasterinc.com\/es\/repuestos\/transferencia-automaticas\/ts-con-gabinete\/dsp-10\/","name":"DSP10 repuesto generador | Power Master Inc.","isPartOf":{"@id":"https:\/\/powermasterinc.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/powermasterinc.com\/es\/repuestos\/transferencia-automaticas\/ts-con-gabinete\/dsp-10\/#primaryimage"},"image":{"@id":"https:\/\/powermasterinc.com\/es\/repuestos\/transferencia-automaticas\/ts-con-gabinete\/dsp-10\/#primaryimage"},"thumbnailUrl":"https:\/\/powermasterinc.com\/es\/wp-content\/uploads\/2026\/02\/dsp10-1.jpg","datePublished":"2019-10-04T17:13:35+00:00","dateModified":"2026-08-21T22:20:31+00:00","description":"DSP-10 | Unidad de Control para Generador (DSP10) \u2014 Unidad de control universal programable para generadores. Monitoreo, protecci\u00f3n y arranque autom\u00e1tico. En stock.","breadcrumb":{"@id":"https:\/\/powermasterinc.com\/es\/repuestos\/transferencia-automaticas\/ts-con-gabinete\/dsp-10\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/powermasterinc.com\/es\/repuestos\/transferencia-automaticas\/ts-con-gabinete\/dsp-10\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/powermasterinc.com\/es\/repuestos\/transferencia-automaticas\/ts-con-gabinete\/dsp-10\/#primaryimage","url":"https:\/\/powermasterinc.com\/es\/wp-content\/uploads\/2026\/02\/dsp10-1.jpg","contentUrl":"https:\/\/powermasterinc.com\/es\/wp-content\/uploads\/2026\/02\/dsp10-1.jpg","width":1000,"height":1000,"caption":"DSP10 repuesto para generadores y motores industriales"},{"@type":"BreadcrumbList","@id":"https:\/\/powermasterinc.com\/es\/repuestos\/transferencia-automaticas\/ts-con-gabinete\/dsp-10\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/powermasterinc.com\/es\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/powermasterinc.com\/es\/tienda-proveedor-repuestos-para-generadores-de-energia\/"},{"@type":"ListItem","position":3,"name":"DSP-10 | Unidad de Control para Generador"}]},{"@type":"WebSite","@id":"https:\/\/powermasterinc.com\/es\/#website","url":"https:\/\/powermasterinc.com\/es\/","name":"Power Master Inc.","description":"Todo en un solo Lugar | \u00a1Para todas sus necesidades de generaci\u00f3n el\u00e9ctrica!","publisher":{"@id":"https:\/\/powermasterinc.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/powermasterinc.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/powermasterinc.com\/es\/#organization","name":"Power Master International","url":"https:\/\/powermasterinc.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/powermasterinc.com\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Power Master International"},"image":{"@id":"https:\/\/powermasterinc.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Power-Master-International-2113343258712341\/"]}]}},"_links":{"self":[{"href":"https:\/\/powermasterinc.com\/es\/wp-json\/wp\/v2\/product\/6984","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/powermasterinc.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/powermasterinc.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/powermasterinc.com\/es\/wp-json\/wp\/v2\/comments?post=6984"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/powermasterinc.com\/es\/wp-json\/wp\/v2\/media\/15904"}],"wp:attachment":[{"href":"https:\/\/powermasterinc.com\/es\/wp-json\/wp\/v2\/media?parent=6984"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/powermasterinc.com\/es\/wp-json\/wp\/v2\/product_brand?post=6984"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/powermasterinc.com\/es\/wp-json\/wp\/v2\/product_cat?post=6984"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/powermasterinc.com\/es\/wp-json\/wp\/v2\/product_tag?post=6984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}