{"id":6590,"date":"2019-04-25T17:57:53","date_gmt":"2019-04-25T17:57:53","guid":{"rendered":"https:\/\/powermasterinc.com\/?post_type=product&#038;p=6590"},"modified":"2026-08-21T22:10:34","modified_gmt":"2026-08-21T22:10:34","slug":"tcs2p125-22","status":"publish","type":"product","link":"https:\/\/powermasterinc.com\/es\/repuestos\/transferencia-automaticas\/automatico-y-manual\/tcs2p125-22\/","title":{"rendered":"TCS2P125-22 | Transferencia Automatica 2 Polos | 125 Amperios"},"content":{"rendered":"<p>El TCS2P125-22 es una Transferencia Automatica con controlador TC-V2 integrado, clasificado para 2 polos y 125 amperios. Dise\u00f1ado para la conmutaci\u00f3n entre la red el\u00e9ctrica (utilidad) y el generador de reserva en instalaciones de repetidoras de telefon\u00eda celular, aplicaciones residenciales y comerciales ligeras.<\/p>\n<p>La unidad monitorea tanto la fuente normal como la de reserva en busca de condiciones de sobrevoltaje (OV) y bajo voltaje (UV). Fabricado con pl\u00e1sticos clasificados UL 94V-0. El voltaje de operaci\u00f3n es de 110\/220V AC a 50\/60 Hz. El rango de temperatura de operaci\u00f3n es de -20\u00b0C a +60\u00b0C. La humedad relativa m\u00e1xima es del 95%.<\/p>\n","protected":false},"excerpt":{"rendered":"<ul>\n<li><strong>Fabricado con pl\u00e1sticos UL 94V-0<\/strong><\/li>\n<li><strong>Operaci\u00f3n el\u00e9ctrica<\/strong> y retenci\u00f3n mec\u00e1nica<\/li>\n<li><strong>Voltaje de operaci\u00f3n de la bobina:<\/strong> 110\/220 Vac \u00b120%<\/li>\n<li><strong>Monitoreo de sobrevoltaje (OV) y bajo voltaje (UV)<\/strong> en fuente Normal y de Reserva<\/li>\n<li><strong>Tama\u00f1o compacto,<\/strong> liviano y bajo consumo de energ\u00eda<\/li>\n<li><strong>Retardo de tiempo ajustable<\/strong> en posici\u00f3n OFF durante la transferencia<\/li>\n<li><strong>Dise\u00f1ado<\/strong> para repetidoras de telefon\u00eda celular y aplicaciones industriales y residenciales<\/li>\n<li><strong>Operaci\u00f3n el\u00e9ctrica o manual,<\/strong> contactos de retenci\u00f3n mec\u00e1nica (Transici\u00f3n abierta) con tiempo ajustable en neutro<\/li>\n<\/ul>\n","protected":false},"featured_media":15929,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_joinchat":[]},"product_brand":[],"product_cat":[298],"product_tag":[296,238,297,1088],"class_list":["post-6590","product","type-product","status-publish","has-post-thumbnail","product_cat-automatico-y-manual","product_tag-advr","product_tag-avr","product_tag-mcpherson-controls","product_tag-tcs2p125-22","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>transferencia autom\u00e1tica TCS2P125-22 | Power Master Inc.<\/title>\n<meta name=\"description\" content=\"TCS2P125-22 | Interruptor de Transferencia 2 Polos | 125 Amperios (TCS2P125-22) \u2014 Interruptor de transferencia manual\/autom\u00e1tico Mcpherson Controls, 125A. Dise\u00f1o modular. En stock.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/powermasterinc.com\/es\/repuestos\/transferencia-automaticas\/automatico-y-manual\/tcs2p125-22\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"transferencia autom\u00e1tica TCS2P125-22 | Power Master Inc.\" \/>\n<meta property=\"og:description\" content=\"TCS2P125-22 | Interruptor de Transferencia 2 Polos | 125 Amperios (TCS2P125-22) \u2014 Interruptor de transferencia manual\/autom\u00e1tico Mcpherson Controls, 125A. Dise\u00f1o modular. En stock.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/powermasterinc.com\/es\/repuestos\/transferencia-automaticas\/automatico-y-manual\/tcs2p125-22\/\" \/>\n<meta property=\"og:site_name\" content=\"Power Master Inc.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Power-Master-International-2113343258712341\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-21T22:10:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/powermasterinc.com\/es\/wp-content\/uploads\/2026\/02\/TCS2P-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/powermasterinc.com\\\/es\\\/repuestos\\\/transferencia-automaticas\\\/automatico-y-manual\\\/tcs2p125-22\\\/\",\"url\":\"https:\\\/\\\/powermasterinc.com\\\/es\\\/repuestos\\\/transferencia-automaticas\\\/automatico-y-manual\\\/tcs2p125-22\\\/\",\"name\":\"transferencia autom\u00e1tica TCS2P125-22 | Power Master Inc.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/powermasterinc.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/powermasterinc.com\\\/es\\\/repuestos\\\/transferencia-automaticas\\\/automatico-y-manual\\\/tcs2p125-22\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/powermasterinc.com\\\/es\\\/repuestos\\\/transferencia-automaticas\\\/automatico-y-manual\\\/tcs2p125-22\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/powermasterinc.com\\\/es\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/TCS2P-1.jpg\",\"datePublished\":\"2019-04-25T17:57:53+00:00\",\"dateModified\":\"2026-08-21T22:10:34+00:00\",\"description\":\"TCS2P125-22 | Interruptor de Transferencia 2 Polos | 125 Amperios (TCS2P125-22) \u2014 Interruptor de transferencia manual\\\/autom\u00e1tico Mcpherson Controls, 125A. Dise\u00f1o modular. En stock.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/powermasterinc.com\\\/es\\\/repuestos\\\/transferencia-automaticas\\\/automatico-y-manual\\\/tcs2p125-22\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/powermasterinc.com\\\/es\\\/repuestos\\\/transferencia-automaticas\\\/automatico-y-manual\\\/tcs2p125-22\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/powermasterinc.com\\\/es\\\/repuestos\\\/transferencia-automaticas\\\/automatico-y-manual\\\/tcs2p125-22\\\/#primaryimage\",\"url\":\"https:\\\/\\\/powermasterinc.com\\\/es\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/TCS2P-1.jpg\",\"contentUrl\":\"https:\\\/\\\/powermasterinc.com\\\/es\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/TCS2P-1.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"Interruptor de transferencia autom\u00e1tica TCS2P125-22 Mcpherson\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/powermasterinc.com\\\/es\\\/repuestos\\\/transferencia-automaticas\\\/automatico-y-manual\\\/tcs2p125-22\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/powermasterinc.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/powermasterinc.com\\\/es\\\/tienda-proveedor-repuestos-para-generadores-de-energia\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"TCS2P125-22 | Transferencia Automatica 2 Polos | 125 Amperios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/powermasterinc.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/powermasterinc.com\\\/es\\\/\",\"name\":\"Power Master Inc.\",\"description\":\"Todo en un solo Lugar | \u00a1Para todas sus necesidades de generaci\u00f3n el\u00e9ctrica!\",\"publisher\":{\"@id\":\"https:\\\/\\\/powermasterinc.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/powermasterinc.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/powermasterinc.com\\\/es\\\/#organization\",\"name\":\"Power Master International\",\"url\":\"https:\\\/\\\/powermasterinc.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/powermasterinc.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Power Master International\"},\"image\":{\"@id\":\"https:\\\/\\\/powermasterinc.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Power-Master-International-2113343258712341\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"transferencia autom\u00e1tica TCS2P125-22 | Power Master Inc.","description":"TCS2P125-22 | Interruptor de Transferencia 2 Polos | 125 Amperios (TCS2P125-22) \u2014 Interruptor de transferencia manual\/autom\u00e1tico Mcpherson Controls, 125A. Dise\u00f1o modular. En stock.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/powermasterinc.com\/es\/repuestos\/transferencia-automaticas\/automatico-y-manual\/tcs2p125-22\/","og_locale":"es_ES","og_type":"article","og_title":"transferencia autom\u00e1tica TCS2P125-22 | Power Master Inc.","og_description":"TCS2P125-22 | Interruptor de Transferencia 2 Polos | 125 Amperios (TCS2P125-22) \u2014 Interruptor de transferencia manual\/autom\u00e1tico Mcpherson Controls, 125A. Dise\u00f1o modular. En stock.","og_url":"https:\/\/powermasterinc.com\/es\/repuestos\/transferencia-automaticas\/automatico-y-manual\/tcs2p125-22\/","og_site_name":"Power Master Inc.","article_publisher":"https:\/\/www.facebook.com\/Power-Master-International-2113343258712341\/","article_modified_time":"2026-08-21T22:10:34+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/powermasterinc.com\/es\/wp-content\/uploads\/2026\/02\/TCS2P-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/powermasterinc.com\/es\/repuestos\/transferencia-automaticas\/automatico-y-manual\/tcs2p125-22\/","url":"https:\/\/powermasterinc.com\/es\/repuestos\/transferencia-automaticas\/automatico-y-manual\/tcs2p125-22\/","name":"transferencia autom\u00e1tica TCS2P125-22 | Power Master Inc.","isPartOf":{"@id":"https:\/\/powermasterinc.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/powermasterinc.com\/es\/repuestos\/transferencia-automaticas\/automatico-y-manual\/tcs2p125-22\/#primaryimage"},"image":{"@id":"https:\/\/powermasterinc.com\/es\/repuestos\/transferencia-automaticas\/automatico-y-manual\/tcs2p125-22\/#primaryimage"},"thumbnailUrl":"https:\/\/powermasterinc.com\/es\/wp-content\/uploads\/2026\/02\/TCS2P-1.jpg","datePublished":"2019-04-25T17:57:53+00:00","dateModified":"2026-08-21T22:10:34+00:00","description":"TCS2P125-22 | Interruptor de Transferencia 2 Polos | 125 Amperios (TCS2P125-22) \u2014 Interruptor de transferencia manual\/autom\u00e1tico Mcpherson Controls, 125A. Dise\u00f1o modular. En stock.","breadcrumb":{"@id":"https:\/\/powermasterinc.com\/es\/repuestos\/transferencia-automaticas\/automatico-y-manual\/tcs2p125-22\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/powermasterinc.com\/es\/repuestos\/transferencia-automaticas\/automatico-y-manual\/tcs2p125-22\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/powermasterinc.com\/es\/repuestos\/transferencia-automaticas\/automatico-y-manual\/tcs2p125-22\/#primaryimage","url":"https:\/\/powermasterinc.com\/es\/wp-content\/uploads\/2026\/02\/TCS2P-1.jpg","contentUrl":"https:\/\/powermasterinc.com\/es\/wp-content\/uploads\/2026\/02\/TCS2P-1.jpg","width":1000,"height":1000,"caption":"Interruptor de transferencia autom\u00e1tica TCS2P125-22 Mcpherson"},{"@type":"BreadcrumbList","@id":"https:\/\/powermasterinc.com\/es\/repuestos\/transferencia-automaticas\/automatico-y-manual\/tcs2p125-22\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/powermasterinc.com\/es\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/powermasterinc.com\/es\/tienda-proveedor-repuestos-para-generadores-de-energia\/"},{"@type":"ListItem","position":3,"name":"TCS2P125-22 | Transferencia Automatica 2 Polos | 125 Amperios"}]},{"@type":"WebSite","@id":"https:\/\/powermasterinc.com\/es\/#website","url":"https:\/\/powermasterinc.com\/es\/","name":"Power Master Inc.","description":"Todo en un solo Lugar | \u00a1Para todas sus necesidades de generaci\u00f3n el\u00e9ctrica!","publisher":{"@id":"https:\/\/powermasterinc.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/powermasterinc.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/powermasterinc.com\/es\/#organization","name":"Power Master International","url":"https:\/\/powermasterinc.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/powermasterinc.com\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Power Master International"},"image":{"@id":"https:\/\/powermasterinc.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Power-Master-International-2113343258712341\/"]}]}},"_links":{"self":[{"href":"https:\/\/powermasterinc.com\/es\/wp-json\/wp\/v2\/product\/6590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/powermasterinc.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/powermasterinc.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/powermasterinc.com\/es\/wp-json\/wp\/v2\/comments?post=6590"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/powermasterinc.com\/es\/wp-json\/wp\/v2\/media\/15929"}],"wp:attachment":[{"href":"https:\/\/powermasterinc.com\/es\/wp-json\/wp\/v2\/media?parent=6590"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/powermasterinc.com\/es\/wp-json\/wp\/v2\/product_brand?post=6590"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/powermasterinc.com\/es\/wp-json\/wp\/v2\/product_cat?post=6590"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/powermasterinc.com\/es\/wp-json\/wp\/v2\/product_tag?post=6590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}